{"id":1060,"date":"2021-04-16T22:07:54","date_gmt":"2021-04-16T22:07:54","guid":{"rendered":"https:\/\/211md.org\/?page_id=1060"},"modified":"2026-09-01T18:44:00","modified_gmt":"2026-09-01T22:44:00","slug":"wasserrechnungen","status":"publish","type":"page","link":"https:\/\/211md.org\/de\/resources\/utility-assistance\/water-bills\/","title":{"rendered":"Hilfe bei der Bezahlung Ihrer Wasserrechnung"},"content":{"rendered":"<figure data-animation-delay=\"0\" data-animation-duration=\"1\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/stg-maryland211-staging.kinsta.cloud\/wp-content\/uploads\/2025\/08\/5-1-scaled.png\" alt=\"5\" height=\"692\" width=\"2560\" title=\"5\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t\t<p>Wenn Sie eine Benachrichtigung \u00fcber die Wasserabschaltung erhalten haben, k\u00f6nnen Sie m\u00f6glicherweise Unterst\u00fctzung von \u00f6rtlichen Wohlt\u00e4tigkeitsorganisationen und kirchlichen Einrichtungen erhalten. Weitere Informationen finden Sie in der Datenbank f\u00fcr kommunale Hilfsangebote (211 Community Resource Database). Dort k\u00f6nnen Sie lokale Organisationen und Programme finden, die Ihnen helfen k\u00f6nnen.<\/p>\n<a href=\"https:\/\/search.211md.org\/search?query=BV-8900.9300-950&#038;query_label=Water+Service+Payment+Assistance&#038;query_type=taxonomy&#038;entry=search_card&#038;distance=25\" target=\"_blank\" rel=\"noopener\">Find Water Bill Help(opens in new tab)<\/a>\t\n<figure data-animation-delay=\"0\" data-animation-duration=\"1\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/2023\/10\/Food-pantry-box-of-food.jpg\" alt=\"Mann verteilt Essensboxen\" height=\"800\" width=\"1200\" title=\"Vorratskammer mit Lebensmitteln\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<h2>Hilfe bei Wasserrechnungen<\/h2>\n<p>Wenn Sie Hilfe bei der Begleichung Ihrer Wasserrechnung ben\u00f6tigen, ist es wichtig, sich Hilfe zu holen, sobald Sie die finanzielle Notlage erkennen, um zu vermeiden, dass Ihr Wasser abgestellt wird.<\/p>\n<p>Hilfe erhalten Sie \u00fcber:<\/p>\n<ul>\n<li>lokale Wasserhilfsprogramme<\/li>\n<li>Ein Programm zur Senkung der Wasserrechnung f\u00fcr Haushalte mit niedrigem Einkommen ist \u00fcber den Bundesstaat Maryland verf\u00fcgbar.<\/li>\n<li>lokale Organisationen<\/li>\n<li>Zahlungsprogramme \u00fcber Ihr Wasserversorgungsunternehmen<\/li>\n<\/ul>\n<p>Sprechen Sie zun\u00e4chst mit Ihrem Wasserversorger \u00fcber Ihre finanzielle Situation, um eine Abschaltung des Wassers zu vermeiden.<\/p>\n<p>M\u00f6glicherweise k\u00f6nnen Sie das F\u00e4lligkeitsdatum verl\u00e4ngern oder eine andere Zahlungsvereinbarung treffen.<\/p>\n<p>Hier sind einige Beispiele f\u00fcr Wasserhilfsprogramme von Wasserunternehmen und -versorgern in Maryland.<\/p>\n<figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/211md.org\/wp-content\/uploads\/2022\/09\/Family-washing-hands-with-water.jpg\" alt=\"Familie w\u00e4scht sich die H\u00e4nde mit Wasser\" title=\"Familie-H\u00e4ndewaschen-mit-Wasser\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t<\/figure>\n\t<h3>WSSC-Wasserhilfeprogramme<\/h3>\n<p>Wenn beispielsweise WSSC Water (Montgomery und Prince George&#039;s County) Ihr Wasserversorger ist, haben Sie m\u00f6glicherweise Anspruch auf mehrere Hilfsprogramme.<\/p>\n<p>Die <a href=\"https:\/\/www.wsscwater.com\/waterfund\" target=\"_blank\" rel=\"noopener\">Water Fund(opens in new tab)<\/a> provides up to $500 per year to eligible customers. It&#8217;s managed by the United Way of the National Capital Area.<\/p>\n<p>Der Wasserfonds ist ein einkommensabh\u00e4ngiges Programm f\u00fcr Familien mit einem Einkommen bis einschlie\u00dflich 200% der bundesstaatlichen Armutsgrenze. Die Mittel werden nach dem Prinzip \u201eWer zuerst kommt, mahlt zuerst\u201c vergeben. Sind die Kapazit\u00e4ten f\u00fcr einen Monat ersch\u00f6pft, findet der n\u00e4chste Termin am ersten Montag des Folgemonats statt.<\/p>\n<p>WSSC Water bietet au\u00dferdem verl\u00e4ngerte R\u00fcckgabefristen und bequeme <a href=\"https:\/\/www.wsscwater.com\/payplans\" target=\"_blank\" rel=\"noopener\">payment plans(opens in new tab)<\/a>. Die Zahlungspl\u00e4ne k\u00f6nnen auf 36 oder 48 Monate verl\u00e4ngert werden, je nachdem, ob Sie ein vom Customer Assistance Program (CAP) zugelassener Kunde sind.<\/p>\n<p>If you&#8217;re a tenant, you need the landlord&#8217;s (owner&#8217;s) approval to set up a payment plan for your water bill.<\/p>\n<p>M\u00f6glicherweise gibt es in Ihrem Landkreis auch spezielle Programme zur Unterst\u00fctzung bei Zahlungen.<\/p>\n<p>Dies sind nur Beispiele f\u00fcr WSSC Water, aber andere Wasserunternehmen k\u00f6nnen \u00e4hnliche oder zus\u00e4tzliche Hilfsprogramme f\u00fcr Wasser anbieten.<\/p>\n<p>211 kann Ihnen helfen, Programme zu identifizieren, die Ihnen helfen, Wasserrechnungen in Ihrer Gemeinde zu bezahlen.<\/p>\n<h3>Wasserrechnungen der Stadt Baltimore<\/h3>\n<p>Wenn Sie in wohnen\u00a0<a href=\"https:\/\/211md.org\/de\/ressourcen-nach-landkreis\/baltimore-stadt\/\" target=\"_blank\" rel=\"noopener\">Baltimore City(opens in new tab)<\/a>, the Water4All discount program helps create more equitable access to water assistance. It&#8217;s a yearly program. You must reapply every year.<\/p>\n<p><a href=\"https:\/\/www.baltimorecity.gov\/publicworks\/water-bill\/water-bill-assistance\/water4all\" target=\"_blank\" rel=\"noopener\">Water4All(opens in new tab)<\/a> Es handelt sich um ein einkommensabh\u00e4ngiges Programm f\u00fcr Haushalte mit einem Einkommen unterhalb von 200% der bundesstaatlichen Armutsgrenze. Die Einkommensrichtlinien k\u00f6nnen sich zwar \u00e4ndern, aber eine vierk\u00f6pfige Familie aus Baltimore City mit einem Jahreseinkommen von unter $55.500 w\u00e4re aktuell anspruchsberechtigt.<\/p>\n<p>Sind Sie sich nicht sicher, wie viel Sie schulden?\u00a0<a href=\"https:\/\/cityservices.baltimorecity.gov\/water\/\" target=\"_blank\" rel=\"noopener\">Find a water bill in Baltimore City(opens in new tab)<\/a>, with the account number or service address.<\/p>\n<p>M\u00f6glicherweise haben Sie auch Anspruch auf Hilfe durch ein anderes Wasserhilfsprogramm oder eine Gemeinschaftsorganisation.<\/p>\n<p>&nbsp;<\/p>\n<h2>Brauchen Sie noch etwas?<\/h2>\n<p>Unter der Nummer 211 erhalten Sie Informationen und Vermittlungen f\u00fcr weitere wichtige Bed\u00fcrfnisse. Informieren Sie sich \u00fcber verf\u00fcgbare Hilfsprogramme f\u00fcr Lebensmittel, Wohnraum, Unterst\u00fctzung bei den Nebenkosten und vieles mehr!<\/p>\n<p>&nbsp;<\/p>\n\t<a href=\"\/de\/ressourcen\/lebensmittel\/\" target=\"_self\">Nahrung finden<\/a><a href=\"\/de\/ressourcen\/gehause-unterkunft\/\" target=\"_self\">Wohnung finden<\/a><a href=\"https:\/\/211md.org\/de\/ressourcen\/utility-unterstutzung\/\" target=\"_self\">Unterst\u00fctzung bei den Nebenkosten erhalten<\/a><a href=\"\/de\/ressourcen-nach-landkreis\/\" target=\"_self\">Ressourcen nach Landkreis<\/a>\n<h2>\n\t\t\tVerwandte Informationen zu Versorgungsunternehmen\t<\/h2>\n\t\t<h4><a href=\"\/de\/ressourcen\/alterungsbehinderung\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Aging\" target=\"_self\">Altern<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/alterungsbehinderung\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Aging\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Aging-disability-square-c466727102cae71e5f27b8539bb51945-.png\" alt=\"\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/kinder-familien\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Children\" target=\"_self\">Kinder &amp; Familien<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/kinder-familien\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Children\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_211_Icon-Sets_Child-care-square-f3b0d4edab3dcc467fadb5f55f4064c6-.png\" alt=\"Eltern-Kind-Symbol f\u00fcr Kinderbetreuung\" height=\"417\" width=\"417\" title=\"2025_211_Icon Sets_Kinderbetreuung\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"https:\/\/211md.org\/de\/ressourcen\/dienstleistungen-fur-behinderte\/\" target=\"_self\">Behinderung<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"https:\/\/211md.org\/de\/ressourcen\/dienstleistungen-fur-behinderte\/\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_211_Icon-Sets_Disability-2-square-2d52ec248cb1d3b313413ba03d5712a4-.png\" alt=\"Barrierefreiheitssymbol\" height=\"417\" width=\"417\" title=\"2025_211_Icon Sets_Disability 2\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/hausliche-familiare-gewalt\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Domestic\" target=\"_self\">H\u00e4usliche Gewalt<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/hausliche-familiare-gewalt\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Domestic\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_211_Icon-Sets_Domestic-Violence-square-7b597694a6f05fe90cdc376aa573bc63-.png\" alt=\"Haus mit einem Herz in der Mitte (Symbol)\" height=\"417\" width=\"417\" title=\"2025_211_Icon Sets_H\u00e4usliche Gewalt\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/arbeitssuche\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Employment\" target=\"_self\">Besch\u00e4ftigung<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/arbeitssuche\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Employment\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Employment-square-44707bd410e4df10a470bf130ebcea86-.png\" alt=\"\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/gesundheitswesen\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Health%20Care\" target=\"_self\">Gesundheitsvorsorge<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/gesundheitswesen\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Health%20Care\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Health-Care-square-dee98a0060cbe0e7f27eda253fc12679-.png\" alt=\"\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/neu-in-den-usa-und-maryland\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Immigration\" target=\"_self\">Einwanderung<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/neu-in-den-usa-und-maryland\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Immigration\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Immigration-square-8b97b7fdfe5e6071405e216855065118-.png\" alt=\"Einwanderungssymbol\" title=\"2025_MdInfoNet_Icon-Sets_Immigration\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/kinder-familien\/verwandtschaftspflege\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Kinship\" target=\"_self\">Verwandtschaft<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/kinder-familien\/verwandtschaftspflege\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Kinship\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_211_Icon-Sets_Kinship-square-45bdf872866f5735f842c32071109267-.png\" alt=\"Verwandtschaftssymbol\" height=\"417\" width=\"417\" title=\"2025_211_Icon Sets_Verwandtschaft\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/rechtsberatung\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Legal\" target=\"_self\">Rechtsberatung<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/rechtsberatung\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Legal\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Legal-square-18fdf438feb8435588174d9046463257-.png\" alt=\"\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/psychische-gesundheit\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Mental\" target=\"_self\">Psychische Gesundheit<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/psychische-gesundheit\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Mental\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Mental-Health-square-c59b38c4a993a947d4c9280fbe2d2fee-.png\" alt=\"\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/kinder-familien\/ein-baby-haben\/\" target=\"_self\">Schwangerschaft<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/kinder-familien\/ein-baby-haben\/\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Child-Care-square-9df1e1b3f647b6907633e4735715bfda-.png\" alt=\"Kinderwagen-Symbol\" title=\"2025_MdInfoNet_Icon-Sets_Child-Care\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/mdreentry\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Reentry\" target=\"_self\">Wiedereintritt<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/mdreentry\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Reentry\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_211_Icon-Sets_Reentry-square-8676fea38abd920a832f45642fe31cca-.png\" alt=\"Symbol \u201eWiedereintritt\u201c\" height=\"417\" width=\"417\" title=\"2025_211_Icon Sets_Wiedereintritt\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/substanzgebrauch\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Substance\" target=\"_self\">Substanzgebrauch<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/substanzgebrauch\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Substance\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Substance-Abuse-square-4f414f085e657267739c181957754f48-.png\" alt=\"Symbol f\u00fcr Pillen zur Substanzverwendung\" title=\"2025_MdInfoNet_Icon-Sets_Substance-Abuse\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>\n\t\t<h4><a href=\"\/de\/ressourcen\/veteranen\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Veterans\" target=\"_self\">Veteranen<\/a><\/h4><figure itemscope itemtype=\"https:\/\/schema.org\/ImageObject\">\n\t\t\t\t<a href=\"\/de\/ressourcen\/veteranen\/?utm_source=Home&#038;utm_medium=Referral&#038;utm_campaign=211Resources&#038;utm_content=Veterans\" target=\"_self\" itemprop=\"url\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/211md.org\/wp-content\/uploads\/bb-plugin\/cache\/2025_MdInfoNet_Icon-Sets_Rating-square-6e60d00cce4faa8e0a6d4ad7366aa733-.png\" alt=\"\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t<\/figure>","protected":false},"excerpt":{"rendered":"<p>If you have a water shut-off notice, you may be eligible for assistance from local charities and faith-based organizations. Learn more by searching the 211 Community Resource Database to find local organizations and programs that can help. Find Water Bill Help(opens in new tab) Help with water bills If you need help paying your water&hellip;<\/p>","protected":false},"author":8,"featured_media":3288,"parent":932,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"group":[],"class_list":["post-1060","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/pages\/1060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/comments?post=1060"}],"version-history":[{"count":11,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/pages\/1060\/revisions"}],"predecessor-version":[{"id":35055,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/pages\/1060\/revisions\/35055"}],"up":[{"embeddable":true,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/pages\/932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/media\/3288"}],"wp:attachment":[{"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/media?parent=1060"}],"wp:term":[{"taxonomy":"group","embeddable":true,"href":"https:\/\/211md.org\/de\/wp-json\/wp\/v2\/group?post=1060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}